{"id":9,"date":"2019-10-29T10:04:28","date_gmt":"2019-10-29T10:04:28","guid":{"rendered":"https:\/\/demo.casethemes.net\/consultio-immigration\/?page_id=9"},"modified":"2026-05-12T16:44:03","modified_gmt":"2026-05-12T16:44:03","slug":"mineral-explore","status":"publish","type":"page","link":"https:\/\/capstonegeocon.com\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9\" class=\"elementor elementor-9\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d33abac elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"d33abac\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cfbd7a2\" data-id=\"cfbd7a2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-742f7b7 elementor-widget elementor-widget-slider_revolution\" data-id=\"742f7b7\" data-element_type=\"widget\" data-widget_type=\"slider_revolution.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"wp-block-themepunch-revslider\">\n\t\t\t<!-- START Slider 1 REVOLUTION SLIDER 6.6.19 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_1_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_1_1\" style=\"\" data-version=\"6.6.19\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-1\" data-title=\"Slide\" data-thumb=\"\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/ANGOLA-2019-BENTIABA-COPPER-scaled-50x100.jpg\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" src=\"\/\/capstonegeocon.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"ANGOLA-2019-BENTIABA-COPPER\" width=\"2560\" height=\"1182\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/ANGOLA-2019-BENTIABA-COPPER-scaled.jpg\" data-bg=\"p:left center;\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-5\" data-title=\"Slide\" data-thumb=\"\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/DJIBOUTI-2018-BASALT-1-scaled-50x100.jpg\" data-anim=\"d:10;ms:500ms;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/capstonegeocon.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"DJIBOUTI-2018-BASALT\" width=\"2560\" height=\"1707\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/DJIBOUTI-2018-BASALT-1-scaled.jpg\" data-bg=\"p:center bottom;\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-2\" data-title=\"Slide\" data-thumb=\"\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/ZAMBIA-GEMFIELDS-2014-2-scaled-50x100.jpg\" data-anim=\"ms:2000ms;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/capstonegeocon.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"ZAMBIA-GEMFIELDS-2014-2\" width=\"2560\" height=\"1920\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/ZAMBIA-GEMFIELDS-2014-2-scaled.jpg\" data-panzoom=\"d:8000ms;ss:110%;se:100;\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-3\" data-title=\"Slide\" data-thumb=\"\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/ANGOLA-COPPER-LIMESTONE-TERRACE-scaled-50x100.jpg\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"\/\/capstonegeocon.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"ANGOLA-COPPER-LIMESTONE TERRACE\" width=\"2560\" height=\"1707\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/ANGOLA-COPPER-LIMESTONE-TERRACE-scaled.jpg\" data-panzoom=\"d:8000ms;ss:110%;se:100;\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-7\" data-title=\"Slide\" data-thumb=\"\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/DJIBOUTI-2018-GOLD-LST-TERRAIN-4-scaled-50x100.jpg\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"\/\/capstonegeocon.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"DJIBOUTI-2018-GOLD- LST TERRAIN-4\" width=\"2560\" height=\"1707\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/DJIBOUTI-2018-GOLD-LST-TERRAIN-4-scaled.jpg\" data-panzoom=\"d:8000ms;ss:110%;se:100;\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-6\" data-title=\"Slide\" data-thumb=\"\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/MAURITANIA-2019-SAHARA-GOLD-scaled-50x100.jpg\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"\/\/capstonegeocon.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"MAURITANIA-2019-SAHARA-GOLD\" width=\"2560\" height=\"1707\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/MAURITANIA-2019-SAHARA-GOLD-scaled.jpg\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-8\" data-title=\"Slide\" data-thumb=\"\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/MAURITANIA-IRON-2012-4-50x100.jpg\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"\/\/capstonegeocon.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"MAURITANIA-IRON-2012-4\" width=\"1600\" height=\"1063\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/MAURITANIA-IRON-2012-4.jpg\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-9\" data-title=\"Slide\" data-thumb=\"\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/YEMEN-2009-MARIB-MAGNETITE-scaled-50x100.jpg\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"\/\/capstonegeocon.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"YEMEN-2009-MARIB-MAGNETITE\" width=\"2560\" height=\"1920\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/YEMEN-2009-MARIB-MAGNETITE-scaled.jpg\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_1_1',rl:[1240,1024,778,480],el:[650,710,540,480],gw:[1600,1024,778,480],gh:[650,710,540,480],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider11\"]!==undefined) {window.RS_MODULES.modules[\"revslider11\"].once = false;window.revapi1 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-718a5f0 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"718a5f0\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4654186\" data-id=\"4654186\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-73c32f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73c32f0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-df91352\" data-id=\"df91352\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-973e48d elementor-widget elementor-widget-text-editor\" data-id=\"973e48d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 04-12-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Our <span style=\"color: #003300;\"><a style=\"color: #003300;\" href=\"https:\/\/cgcl.in\/\">vast experience<\/a>,<\/span> expertise and profound knowledge shines through every stage of mineral exploration, spanning from target generation, to scoping studies, detailed exploration and project generation. Our comprehensive range of services encompasses the entire spectrum of mineral exploration, from geospatial &amp; reconnaissance studies to identify exploration targets, meticulous geological mapping &amp; mineral prospecting with advanced geoscientific techniques to define these targets, detailed geological exploration, mineral resource modelling, and evaluating mineral project feasibility.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c63a58c\" data-id=\"c63a58c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-870f1ee elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"870f1ee\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 04-12-2023 *\/\n.elementor-widget-image-carousel .swiper,.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure,.elementor-widget-image-carousel .swiper .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized):not(.swiper-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/a4.jpg\" alt=\"geological consultant\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/a3.jpg\" alt=\"mining consultants\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/a2.jpg\" alt=\"mine planning consultant\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/a1.jpg\" alt=\"drone survey\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7a46140 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7a46140\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2db4561\" data-id=\"2db4561\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-50429ab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"50429ab\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d7c76eb\" data-id=\"d7c76eb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c3edbd4\" data-id=\"c3edbd4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a545f07\" data-id=\"a545f07\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-96c1aea elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"96c1aea\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9f858aa\" data-id=\"9f858aa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fb00721 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb00721\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cf7a367\" data-id=\"cf7a367\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c860a37\" data-id=\"c860a37\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-211271c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"211271c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3efe5db\" data-id=\"3efe5db\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4ef32ce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ef32ce\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7506b06\" data-id=\"7506b06\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a68679e\" data-id=\"a68679e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-49eb132\" data-id=\"49eb132\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-e912b99 elementor-widget elementor-widget-image\" data-id=\"e912b99\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 04-12-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"791\" src=\"https:\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/map-1536x791.png\" class=\"attachment-1536x1536 size-1536x1536 wp-image-6370\" alt=\"\" srcset=\"https:\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/map-1536x791.png 1536w, https:\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/map-300x155.png 300w, https:\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/map-1024x528.png 1024w, https:\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/map-768x396.png 768w, https:\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/map-2048x1055.png 2048w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1dd066d elementor-section-stretched elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1dd066d\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7be4a84\" data-id=\"7be4a84\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-103b1f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"103b1f1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a03db3f\" data-id=\"a03db3f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-24a6a24\" data-id=\"24a6a24\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e8cbf20 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e8cbf20\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-177f326\" data-id=\"177f326\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fb83a09\" data-id=\"fb83a09\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f2f41a elementor-section-stretched elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f2f41a\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65618fe\" data-id=\"65618fe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-29ad7ed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29ad7ed\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-687a098\" data-id=\"687a098\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d595e92\" data-id=\"d595e92\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-abf3c72\" data-id=\"abf3c72\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Our vast experience, expertise and profound knowledge shines through every stage of mineral exploration, spanning from target generation, to scoping studies, detailed exploration and project generation. Our comprehensive range of services encompasses the entire spectrum of mineral exploration, from geospatial &amp; reconnaissance studies to identify exploration targets, meticulous geological mapping &amp; mineral prospecting with advanced [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.9 (Yoast SEO v22.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mineral Exploration Excellence by Capstone Geo Consultants<\/title>\n<meta name=\"description\" content=\"Explore the pinnacle of mineral exploration with Capstone Geo Consultants. Our unwavering efficacy and global footprint make us a trusted name in the industry. Discover excellence in mineral resource assessment and consultation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/capstonegeocon.com\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mineral Exploration Excellence by Capstone Geo Consultants\" \/>\n<meta property=\"og:description\" content=\"Discover mineral exploration excellence with Capstone Geo Consultants. Our global footprint ensures precise evaluations and innovative techniques for successful mining projects.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/capstonegeocon.com\/\" \/>\n<meta property=\"og:site_name\" content=\"Capstone Geo Consultants\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T16:44:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/a4.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/capstonegeocon.com\/\",\"url\":\"https:\/\/capstonegeocon.com\/\",\"name\":\"Mineral Exploration Excellence by Capstone Geo Consultants\",\"isPartOf\":{\"@id\":\"https:\/\/capstonegeocon.com\/#website\"},\"datePublished\":\"2019-10-29T10:04:28+00:00\",\"dateModified\":\"2026-05-12T16:44:03+00:00\",\"description\":\"Explore the pinnacle of mineral exploration with Capstone Geo Consultants. Our unwavering efficacy and global footprint make us a trusted name in the industry. Discover excellence in mineral resource assessment and consultation.\",\"breadcrumb\":{\"@id\":\"https:\/\/capstonegeocon.com\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/capstonegeocon.com\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/capstonegeocon.com\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/capstonegeocon.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/capstonegeocon.com\/#website\",\"url\":\"https:\/\/capstonegeocon.com\/\",\"name\":\"Mineral Exploration Excellence by Capstone Geo Consultants\",\"description\":\"Mineral Exploration Consultancy\",\"alternateName\":\"Mineral Exploration Excellence\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/capstonegeocon.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mineral Exploration Excellence by Capstone Geo Consultants","description":"Explore the pinnacle of mineral exploration with Capstone Geo Consultants. Our unwavering efficacy and global footprint make us a trusted name in the industry. Discover excellence in mineral resource assessment and consultation.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/capstonegeocon.com\/","og_locale":"en_US","og_type":"article","og_title":"Mineral Exploration Excellence by Capstone Geo Consultants","og_description":"Discover mineral exploration excellence with Capstone Geo Consultants. Our global footprint ensures precise evaluations and innovative techniques for successful mining projects.","og_url":"https:\/\/capstonegeocon.com\/","og_site_name":"Capstone Geo Consultants","article_modified_time":"2026-05-12T16:44:03+00:00","og_image":[{"url":"https:\/\/capstonegeocon.com\/wp-content\/uploads\/2023\/12\/a4.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"17 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/capstonegeocon.com\/","url":"https:\/\/capstonegeocon.com\/","name":"Mineral Exploration Excellence by Capstone Geo Consultants","isPartOf":{"@id":"https:\/\/capstonegeocon.com\/#website"},"datePublished":"2019-10-29T10:04:28+00:00","dateModified":"2026-05-12T16:44:03+00:00","description":"Explore the pinnacle of mineral exploration with Capstone Geo Consultants. Our unwavering efficacy and global footprint make us a trusted name in the industry. Discover excellence in mineral resource assessment and consultation.","breadcrumb":{"@id":"https:\/\/capstonegeocon.com\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/capstonegeocon.com\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/capstonegeocon.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/capstonegeocon.com\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/capstonegeocon.com\/#website","url":"https:\/\/capstonegeocon.com\/","name":"Mineral Exploration Excellence by Capstone Geo Consultants","description":"Mineral Exploration Consultancy","alternateName":"Mineral Exploration Excellence","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/capstonegeocon.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/capstonegeocon.com\/index.php\/wp-json\/wp\/v2\/pages\/9"}],"collection":[{"href":"https:\/\/capstonegeocon.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/capstonegeocon.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/capstonegeocon.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/capstonegeocon.com\/index.php\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":376,"href":"https:\/\/capstonegeocon.com\/index.php\/wp-json\/wp\/v2\/pages\/9\/revisions"}],"predecessor-version":[{"id":21737,"href":"https:\/\/capstonegeocon.com\/index.php\/wp-json\/wp\/v2\/pages\/9\/revisions\/21737"}],"wp:attachment":[{"href":"https:\/\/capstonegeocon.com\/index.php\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}